{"id":883,"date":"2025-12-31T07:18:09","date_gmt":"2025-12-31T07:18:09","guid":{"rendered":"https:\/\/new.borsehung.de\/product\/oil-separator-ea888-gen2-low-power\/"},"modified":"2026-03-10T07:21:47","modified_gmt":"2026-03-10T07:21:47","slug":"oil-separator-ea888-gen2-low-power","status":"publish","type":"product","link":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/","title":{"rendered":"Oil separator; EA888 gen2; low power"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":884,"template":"","meta":[],"products":[137,139],"class_list":["post-883","product","type-product","status-publish","has-post-thumbnail","hentry","products-volkswagen-engine-parts","products-filtration-system-volkswagen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oil separator; EA888 gen2; low power - Borsehung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oil separator; EA888 gen2; low power - Borsehung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/\" \/>\n<meta property=\"og:site_name\" content=\"Borsehung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Borsehung\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T07:21:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"1092\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/\",\"url\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/\",\"name\":\"Oil separator; EA888 gen2; low power - Borsehung\",\"isPartOf\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp\",\"datePublished\":\"2025-12-31T07:18:09+00:00\",\"dateModified\":\"2026-03-10T07:21:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#primaryimage\",\"url\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp\",\"contentUrl\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp\",\"width\":1456,\"height\":1092},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.borsehung.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oil separator; EA888 gen2; low power\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.borsehung.de\/en\/#website\",\"url\":\"https:\/\/www.borsehung.de\/en\/\",\"name\":\"Borsehung\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.borsehung.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.borsehung.de\/en\/#organization\",\"name\":\"Borsehung\",\"url\":\"https:\/\/www.borsehung.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Borsehung\"},\"image\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Borsehung\",\"https:\/\/www.youtube.com\/@Borsehung\",\"https:\/\/www.tiktok.com\/@Borsehung\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oil separator; EA888 gen2; low power - Borsehung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/","og_locale":"en_US","og_type":"article","og_title":"Oil separator; EA888 gen2; low power - Borsehung","og_url":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/","og_site_name":"Borsehung","article_publisher":"https:\/\/www.facebook.com\/Borsehung","article_modified_time":"2026-03-10T07:21:47+00:00","og_image":[{"width":1456,"height":1092,"url":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/","url":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/","name":"Oil separator; EA888 gen2; low power - Borsehung","isPartOf":{"@id":"https:\/\/www.borsehung.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#primaryimage"},"image":{"@id":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#primaryimage"},"thumbnailUrl":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp","datePublished":"2025-12-31T07:18:09+00:00","dateModified":"2026-03-10T07:21:47+00:00","breadcrumb":{"@id":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#primaryimage","url":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp","contentUrl":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/Oil-separator.webp","width":1456,"height":1092},{"@type":"BreadcrumbList","@id":"https:\/\/www.borsehung.de\/en\/volkswagen-engine-parts\/oil-separator-ea888-gen2-low-power\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.borsehung.de\/en\/"},{"@type":"ListItem","position":2,"name":"Oil separator; EA888 gen2; low power"}]},{"@type":"WebSite","@id":"https:\/\/www.borsehung.de\/en\/#website","url":"https:\/\/www.borsehung.de\/en\/","name":"Borsehung","description":"","publisher":{"@id":"https:\/\/www.borsehung.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.borsehung.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.borsehung.de\/en\/#organization","name":"Borsehung","url":"https:\/\/www.borsehung.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png","contentUrl":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png","width":512,"height":512,"caption":"Borsehung"},"image":{"@id":"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Borsehung","https:\/\/www.youtube.com\/@Borsehung","https:\/\/www.tiktok.com\/@Borsehung"]}]}},"_links":{"self":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/product\/883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/media\/884"}],"wp:attachment":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/media?parent=883"}],"wp:term":[{"taxonomy":"products","embeddable":true,"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/products?post=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}