{"id":627,"date":"2025-12-22T09:53:06","date_gmt":"2025-12-22T09:53:06","guid":{"rendered":"https:\/\/new.borsehung.de\/quality\/"},"modified":"2025-12-22T09:53:06","modified_gmt":"2025-12-22T09:53:06","slug":"quality","status":"publish","type":"page","link":"https:\/\/www.borsehung.de\/en\/quality\/","title":{"rendered":"Quality"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/fronteditor.php","meta":{"footnotes":""},"class_list":["post-627","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>All parts have a four-year warranty - Borsehung<\/title>\n<meta name=\"description\" content=\"Borsehung provides you with high-quality products, all backed by a four-year warranty.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.borsehung.de\/en\/quality\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"All parts have a four-year warranty - Borsehung\" \/>\n<meta property=\"og:description\" content=\"Borsehung provides you with high-quality products, all backed by a four-year warranty.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.borsehung.de\/en\/quality\/\" \/>\n<meta property=\"og:site_name\" content=\"Borsehung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Borsehung\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.borsehung.de\/en\/quality\/\",\"url\":\"https:\/\/www.borsehung.de\/en\/quality\/\",\"name\":\"All parts have a four-year warranty - Borsehung\",\"isPartOf\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/#website\"},\"datePublished\":\"2025-12-22T09:53:06+00:00\",\"description\":\"Borsehung provides you with high-quality products, all backed by a four-year warranty.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/quality\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.borsehung.de\/en\/quality\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.borsehung.de\/en\/quality\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.borsehung.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quality\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.borsehung.de\/en\/#website\",\"url\":\"https:\/\/www.borsehung.de\/en\/\",\"name\":\"Borsehung\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.borsehung.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.borsehung.de\/en\/#organization\",\"name\":\"Borsehung\",\"url\":\"https:\/\/www.borsehung.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Borsehung\"},\"image\":{\"@id\":\"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Borsehung\",\"https:\/\/www.youtube.com\/@Borsehung\",\"https:\/\/www.tiktok.com\/@Borsehung\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"All parts have a four-year warranty - Borsehung","description":"Borsehung provides you with high-quality products, all backed by a four-year warranty.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.borsehung.de\/en\/quality\/","og_locale":"en_US","og_type":"article","og_title":"All parts have a four-year warranty - Borsehung","og_description":"Borsehung provides you with high-quality products, all backed by a four-year warranty.","og_url":"https:\/\/www.borsehung.de\/en\/quality\/","og_site_name":"Borsehung","article_publisher":"https:\/\/www.facebook.com\/Borsehung","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.borsehung.de\/en\/quality\/","url":"https:\/\/www.borsehung.de\/en\/quality\/","name":"All parts have a four-year warranty - Borsehung","isPartOf":{"@id":"https:\/\/www.borsehung.de\/en\/#website"},"datePublished":"2025-12-22T09:53:06+00:00","description":"Borsehung provides you with high-quality products, all backed by a four-year warranty.","breadcrumb":{"@id":"https:\/\/www.borsehung.de\/en\/quality\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.borsehung.de\/en\/quality\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.borsehung.de\/en\/quality\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.borsehung.de\/en\/"},{"@type":"ListItem","position":2,"name":"Quality"}]},{"@type":"WebSite","@id":"https:\/\/www.borsehung.de\/en\/#website","url":"https:\/\/www.borsehung.de\/en\/","name":"Borsehung","description":"","publisher":{"@id":"https:\/\/www.borsehung.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.borsehung.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.borsehung.de\/en\/#organization","name":"Borsehung","url":"https:\/\/www.borsehung.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png","contentUrl":"https:\/\/www.borsehung.de\/wp-content\/uploads\/2025\/12\/cropped-favicon.png","width":512,"height":512,"caption":"Borsehung"},"image":{"@id":"https:\/\/www.borsehung.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Borsehung","https:\/\/www.youtube.com\/@Borsehung","https:\/\/www.tiktok.com\/@Borsehung"]}]}},"_links":{"self":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/pages\/627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/comments?post=627"}],"version-history":[{"count":0,"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/pages\/627\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.borsehung.de\/en\/wp-json\/wp\/v2\/media?parent=627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}